{"id":5004,"date":"2012-03-14T00:10:44","date_gmt":"2012-03-13T23:10:44","guid":{"rendered":"http:\/\/www.warlandia.it\/blog\/?p=5004"},"modified":"2019-10-24T12:52:27","modified_gmt":"2019-10-24T10:52:27","slug":"ahuitzotl","status":"publish","type":"post","link":"https:\/\/www.warlandia.it\/magazine\/2012\/03\/14\/ahuitzotl\/","title":{"rendered":"Ahuitzotl"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ancora mostruose creature da Enrico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;ahuitzotl o ahuizotl \u00e8 un mostro dell&#8217;immaginario azteco e poi messicano. E&#8217; una creatura di piccole dimensioni, simile alla lontra, con la pelle lucida e viscida. Vive sul fondo degli stagni e dei laghi e attira le sue prede col suo canto, simile a quello di un neonato. Sue catture preferite sono gli esseri umani.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"610\" height=\"320\" src=\"https:\/\/www.warlandia.it\/magazine\/wp-content\/uploads\/2012\/03\/ahuitzotl.jpg\" alt=\"\" class=\"wp-image-11111\" srcset=\"https:\/\/www.warlandia.it\/magazine\/wp-content\/uploads\/2012\/03\/ahuitzotl.jpg 610w, https:\/\/www.warlandia.it\/magazine\/wp-content\/uploads\/2012\/03\/ahuitzotl-300x157.jpg 300w\" sizes=\"auto, (max-width: 610px) 100vw, 610px\" \/><figcaption>Ahuitzotl<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;ahuitzotl \u00e8 in grado di catturarli e di portarli nella sua tana sul fondo, perch\u00e9 \u00e8 dotato di zampe prensili e persino di una mano, simile a quella umana, all&#8217;estremit\u00e0 della coda. E&#8217; ghiotto di occhi, denti e unghie umani.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per ingraziarselo, nel passato i pescatori messicani gettavano nelle acque dei laghi una parte del pesce, come offerta al Guardiano del lago.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Enrico Di Giacomo<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;ahuitzotl o ahuizotl \u00e8 un mostro dell&#8217;immaginario azteco e poi messicano. E&#8217; una creatura di piccole dimensioni, simile alla lontra, con la pelle lucida e viscida. Vive sul fondo degli stagni e dei laghi e attira le sue prede col suo canto, simile a quello di un neonato. Sue catture preferite sono gli esseri umani.<\/p>\n","protected":false},"author":1,"featured_media":10434,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","footnotes":""},"categories":[36],"tags":[6],"class_list":["post-5004","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-creature","tag-fantasy","latest_post"],"_links":{"self":[{"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/posts\/5004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/comments?post=5004"}],"version-history":[{"count":3,"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/posts\/5004\/revisions"}],"predecessor-version":[{"id":11112,"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/posts\/5004\/revisions\/11112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/media\/10434"}],"wp:attachment":[{"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/media?parent=5004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/categories?post=5004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/tags?post=5004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}