{"id":4175,"date":"2011-06-26T00:10:42","date_gmt":"2011-06-26T00:10:42","guid":{"rendered":"http:\/\/www.warlandia.it\/blog\/?p=4175"},"modified":"2019-11-04T13:19:33","modified_gmt":"2019-11-04T12:19:33","slug":"da-lost-a-lo-hobbit-evangeline-lilly","status":"publish","type":"post","link":"https:\/\/www.warlandia.it\/magazine\/2011\/06\/26\/da-lost-a-lo-hobbit-evangeline-lilly\/","title":{"rendered":"Da Lost a Lo Hobbit: Evangeline Lilly"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">L&#8217;attesissimo film <a href=\"https:\/\/www.warlandia.it\/magazine\/2010\/04\/28\/lo-hobbit-film\/\">Lo Hobbit<\/a>, ispirato al famoso romanzo di <strong>Tolkien <\/strong>dall&#8217;omonimo titolo, fa parlare ancora di se gi\u00e0 in fase di realizzazione.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"610\" height=\"320\" src=\"https:\/\/www.warlandia.it\/magazine\/wp-content\/uploads\/2011\/06\/evangeline-lilly-the-hobbit.jpg\" alt=\"\" class=\"wp-image-11655\" srcset=\"https:\/\/www.warlandia.it\/magazine\/wp-content\/uploads\/2011\/06\/evangeline-lilly-the-hobbit.jpg 610w, https:\/\/www.warlandia.it\/magazine\/wp-content\/uploads\/2011\/06\/evangeline-lilly-the-hobbit-300x157.jpg 300w\" sizes=\"auto, (max-width: 610px) 100vw, 610px\" \/><figcaption>Da Lost a Lo Hobbit: Evangeline Lilly<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Ancora informazioni rubate online: il famoso <strong>PREQUEL <\/strong>de <a href=\"https:\/\/www.warlandia.it\/magazine\/2005\/05\/01\/il-signore-degli-anelli-una-recensione-speciale\/\">Il Signore degli Anell<\/a>i continua a far notizia. Tempo fa abbiamo avuto il piacere di mostrarvi un video in cui il regista Peter Jackson ci mostravo il backstage del film che sta realizzando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Evangeline Lilly,<\/strong> protagonista femminile della fortunatissima serie TV <strong>LOST<\/strong>, sar\u00e0 una bella elfetta in <strong>Lo Hobbit<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Interpreter\u00e0 Tauriel, letteralmente figlia di Bosco Atro, un&#8217;elfa silvana non prevista dalla narrazione originale. Sar\u00e0 affiancata da Orlando Bloom ancora interprete di Legolas, come gi\u00e0 avvenuto nel Signore degli Anelli.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il regista Peter Jackson lo ha annunciato su Facebook creando molta attesa fra gli appassionati.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evangeline Lilly, protagonista femminile della fortunatissima serie TV LOST, sar\u00e0 una bella elfetta in Lo Hobbit.<\/p>\n","protected":false},"author":1,"featured_media":11653,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","footnotes":""},"categories":[8],"tags":[23,82],"class_list":["post-4175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cinema","tag-film","tag-tv","latest_post"],"_links":{"self":[{"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/posts\/4175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/comments?post=4175"}],"version-history":[{"count":3,"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/posts\/4175\/revisions"}],"predecessor-version":[{"id":11656,"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/posts\/4175\/revisions\/11656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/media\/11653"}],"wp:attachment":[{"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/media?parent=4175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/categories?post=4175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/tags?post=4175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}