{"id":3139,"date":"2008-03-16T15:00:00","date_gmt":"2008-03-16T15:00:00","guid":{"rendered":"http:\/\/www.warlandia.it\/asp\/articoli.asp?action=mostra&#038;id=223"},"modified":"2019-12-16T15:29:19","modified_gmt":"2019-12-16T14:29:19","slug":"il-paladino-capitolo-17-le-leggende-del-passato","status":"publish","type":"post","link":"https:\/\/www.warlandia.it\/magazine\/2008\/03\/16\/il-paladino-capitolo-17-le-leggende-del-passato\/","title":{"rendered":"IL PALADINO &#8211; Capitolo 17- Le leggende del passato"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>A quel punto l&#8217;orda dei non-morti inizi\u00f2 a penetrare nella citt\u00e0, trovando per\u00f2 una strenua difesa: i nostri soldati, compatti, stavano cercando col massimo delle loro forze di resistere. La prima fase della battaglia si svolse tutta nella Valle degli Eroi: i due schieramenti si scontrarono con inaudita violenza per molti minuti, durante i quali ci furono parecchie vittime per ambo i lati. Stormwind riusciva a tenere i non-morti ancora fuori le mura, bench\u00e9 si notasse che col passare del tempo stessero arretrando di poco a poco verso l&#8217;interno. <\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"610\" height=\"320\" src=\"https:\/\/www.warlandia.it\/magazine\/wp-content\/uploads\/2010\/07\/il-paladino-naemor.jpg\" alt=\"\" class=\"wp-image-12457\" srcset=\"https:\/\/www.warlandia.it\/magazine\/wp-content\/uploads\/2010\/07\/il-paladino-naemor.jpg 610w, https:\/\/www.warlandia.it\/magazine\/wp-content\/uploads\/2010\/07\/il-paladino-naemor-300x157.jpg 300w\" sizes=\"auto, (max-width: 610px) 100vw, 610px\" \/><figcaption>Naemor il paladino &#8211; audiolibro<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Sulle mura, dove mi trovavo, era un pandemonio: i non-morti rimasti fuori alle mura issarono scale lungo queste e vi salirono, cercando di conquistarle. Ci trovammo in vantaggio per poco, perch\u00e9 inizialmente salivano per le scale solo ghoul, che i nostri arcieri uccidevano facilmente prima che salissero fino in cima. Le difficolt\u00e0 iniziarono quando per le scale salirono gli orchi, che si dimostrarono resistenti alle frecce. Questi, riuscirono a salire sulle mura, e ingaggiare combattimenti corpo a corpo cogli arcieri, che vennero uccisi, non essendo per nulla adatti a questo tipo di combattimento. Io che mi trovavo li cercai disperatamente di salvarli, uccidendo quantit\u00e0 abnormi di orchi, ma questi sembravano riprodursi a vista d&#8217;occhio. Finalmente i fanti di Stormwind iniziarono a dare anche loro la scalata alle mura dall&#8217;interno, salendo per i corridoi laterali. Mi trovai in una brutta situazione: essendo nella parte centrale delle mura, praticamente la parte al di sopra del portale ormai distrutto, mi ritrovai accerchiata dagli orchi, mentre gli aiuti iniziavano a giungere solo dalle due ali laterali, che per\u00f2 erano molto distanti da me. Ma nonostante la superiorit\u00e0 numerica non ebbero modo di uccidermi. Con rapide combinazioni di fuoco e ghiaccio tenni a dovuta distanza tutti i nemici e li uccisi prima che potessero toccarmi; nei casi pi\u00f9 critici creavo una barriera di ghiaccio intorno a me per difendermi. Sotto di me, invece, la situazione era ancora in stallo con entrambi gli schieramenti che si uccidevano ancora lungo la linea divisoria tra la citt\u00e0 e la foresta. I generali nemici, per\u00f2, seppero sfruttare al meglio la conquista delle mura, perch\u00e9 inviarono l\u00ec la maggior parte dei soldati. Cos\u00ec le truppe di soccorso che salivano sulle mura dai corridoi laterali, dapprima furono in vantaggio, ma poi furono costrette ad arretrare per l&#8217;evidente superiorit\u00e0 numerica. La mia situazione peggior\u00f2 quando vidi sbucare da una di quelle scale maledette, quello che doveva essere il loro campione. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"610\" height=\"320\" src=\"https:\/\/www.warlandia.it\/magazine\/wp-content\/uploads\/2010\/04\/naemor-podcast.jpg\" alt=\"\" class=\"wp-image-12659\" srcset=\"https:\/\/www.warlandia.it\/magazine\/wp-content\/uploads\/2010\/04\/naemor-podcast.jpg 610w, https:\/\/www.warlandia.it\/magazine\/wp-content\/uploads\/2010\/04\/naemor-podcast-300x157.jpg 300w\" sizes=\"auto, (max-width: 610px) 100vw, 610px\" \/><figcaption>Naemor PODCAST de Il Paladino<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Era un orco pi\u00f9 alto degli altri e con una muscolatura ben sviluppata. Portava nella mano destra una mazza enorme, mentre nella sinistra uno scudo di metallo. Punt\u00f2 diretto a me: contrastai i suoi colpi solo infondendo il bastone di magia, altrimenti sarebbe andato in mille pezzi; ma i suoi movimenti erano velocissimi, e mi costrinsero ad arretrare fino al bordo. Ero tanto applicata a parare e attaccare con la staffa che mi resi conto di essere arrivata al limite delle mura solo quando toccai con la schiena il muretto sotto il quale la battaglia infuriava. Mi bast\u00f2 la distrazione di voltarmi per capire cosa avessi toccato, che quello mi colp\u00ec nella pancia con un colpo violentissimo tanto da farmi sbalzare e volare gi\u00f9 dalle mura. Fortuna che non caddi tra i combattenti, ma caddi nel fossato d&#8217;acqua, attenuando l&#8217;impatto.<br> &#8220;Dama Prinewind!&#8221; sentii urlare il reggente,che combatteva in prima linea, mentre mi vedeva volare in basso.<br> Scesi di poco sotto il livello dell&#8217;acqua, e riemersi bagnata e adirata. Mentre raggiungevo a nuoto la riva, per poi poter tornare nel fulcro della battaglia, schizzarono da fuori le mura altri massi giganti che andarono ad impattare contro le abitazioni dietro la valle. Localizzai l&#8217;orco che mi aveva fatto male, e decisi di fargliela pagare. Era ancora sulle mura, ma si era spostato lungo l&#8217;ala destra che scendeva verso la piazza di Stormwind. Evocai il cavallo e iniziai a galoppare in quella direzione, risalendo le mura dal corridoio che partiva dal fossato, per poi ridiscendere per il corridoio che portava dritti nella piazza, situato pi\u00f9 a destra. Era un punto debole della citt\u00e0 che avevano sfruttato alla grande: infatti usando i corridoi che dalla citt\u00e0 portavano sulle mura, avevano evitato di penetrare direttamente dal ponte, dove avevano trovato una difesa eccellente. Aggirandola in questo modo avrebbero potuto attaccare da due lati l&#8217;esercito di Stormwind, cio\u00e8 dall&#8217;esterno, e, paradossalmente, dall&#8217;interno della citt\u00e0 stessa. Mentre raggiungevo l&#8217;orco e galoppavo tra i nemici non esitai a ucciderne il maggior numero con incantesimi ad area: cercavo sempre per\u00f2 di limitarmi. Cos\u00ec, mentre gli abomini sul ponte della Valle degli Eroi combattevano contro i nostri soldati al confine tra citt\u00e0 e foresta, la parte orchesca dell&#8217;esercito nemico era penetrato nella piazza principale della citt\u00e0 sfruttando le mura, e ivi combatteva contro altri soldati. Qui decisi di impegnarmi sul serio, perch\u00e9 se avessero sfondato da quella parte la citt\u00e0 sarebbe stata praticamente persa. Presi di mira l&#8217;orco: gli lanciai prima una sfera di ghiaccio, colpendolo in pieno, poi lo bloccai in scaglie di ghiaccio affilatissime, e iniziai a bombardarlo con tutto il fuoco a mia disposizione. Mor\u00ec in pochissimo tempo.<br> &#8220;Non perdiamoci d&#8217;animo! Contrastiamoli!!&#8221;<br> Mi assicurai che i corridoi che portavano alle mura fossero ben difesi, prima di dirigermi verso il centro della citt\u00e0, per capire se anche l\u00ec avevano sfondato. Lo trovai quasi vuoto: tutto l&#8217;esercito era riverso tra il ponte e le mura. Qui per\u00f2 vi trovai il reggente ferito seriamente:<br> &#8220;Dama! Siete viva!&#8221; mi url\u00f2.<br> &#8220;Gi\u00e0, lei?&#8221;<br> &#8220;Colpito duramente, non posso continuare&#8221;<br> &#8220;Com&#8217;\u00e8 la situazione al ponte?&#8221;<br> &#8220;Anche se in netta inferiorit\u00e0 numerica ne stiamo uccidendo pi\u00f9 noi che loro, ma continuano ad avanzare a vista d&#8217;occhio.&#8221;<br> &#8220;Quindi nel giro di quanto tempo potrebbero essere qui?&#8221;<br> &#8220;Penso tra mezz&#8217;ora&#8221;<br> &#8220;Anche prima se non si manda qualcuno ai corridoi laterali&#8221;<br> &#8220;Come?&#8221; disse quello sorpreso.<br> &#8220;Stanno attaccando da li, e vanno subito rinforzati&#8221;<br> &#8220;Quindi ci vogliono chiudere\u2026oh dannazione questo non va bene\u2026non ci sono abbastanza soldati\u2026ne sono morti tantissimi\u2026&#8221;<br> &#8220;Allora se allentiamo la pressione al ponte rischiamo di perderlo?&#8221;<br> &#8220;Gi\u00e0!&#8221; url\u00f2 disperato.<br> Ancora una volta l&#8217;incredibile stoltezza, ma allo stesso tempo genialit\u00e0 dei non morti venne manifestata: una tremenda esplosione riemp\u00ec l&#8217;aria, un&#8217;esplosione la cui violenza era inaudita.<br> &#8220;Che diamine!?!?&#8221;<br> &#8220;No! Hanno fatto esplodere le mura!&#8221;<br> Raggiungemmo un corridoio laterale, e potemmo constatare che era davvero accaduto questo: le mura non esistevano pi\u00f9, cadute sotto gli esplosivi e i colpi di catapulta nemiche.<br> &#8220;Ma\u2026non-morti che usano dinamite\u2026&#8221; disse il reggente incredulo.<br> &#8220;C&#8217;\u00e8 lo zampino di qualche goblin&#8221;<br> &#8220;Dannazione guarda cosa sta succedendo al ponte!!&#8221; url\u00f2 quello.<br> Le mura, crollando, avevano non solo annullato in confine tra citt\u00e0 e foresta, ma avevano anche ucciso tutti gli orchi che stavano su di esse. Se da un lato questo fatto era positivo, dall&#8217;altro provoc\u00f2 che enormi massi piombarono sul ponte tra i nostri soldati, che furono scavalcati dai nemici, che potevano cos\u00ec tranquillamente penetrare nella citt\u00e0 senza ammazzare i fanti, che venivano accerchiati. Fu allora che, prima che potessi slanciarmi verso i nemici, si sent\u00ec squillare un corno, il cui suono era partito dai meandri della citt\u00e0.<br> &#8220;I paladini!&#8221;<br> L&#8217;esercito di Shadowbreaker sembr\u00f2 sbucare dal nulla, attaccando furiosamente i nemici pi\u00f9 arditi che si erano spinti nella piazza principale. Al ponte la situazione era critica, i nostri soldati ormai venivano ordinati dal loro comandante di ritirarsi nella citt\u00e0, per congiungersi coi paladini. Stavo giust&#8217;appunto per muovermi verso il fulcro della battaglia quando mi venne in mente una cosa.<br> &#8220;Il Re \u00e8 al sicuro?&#8221; domandai al reggente.<br> &#8220;Si, perch\u00e9?&#8221;<br> &#8220;Dove lo avete sistemato?&#8221;<br> &#8220;E&#8217; in una sala nella fortezza a est della citt\u00e0. C&#8217;\u00e8 una scorta d&#8217;elite l\u00ec a difenderlo nel caso\u2026ma perch\u00e9 tanta preoccupazione?&#8221;<br> &#8220;L&#8217;altro giorno o quand&#8217;era ho visto anche un plotone di cavalieri della morte\u2026non vorrei che fossero stati portati solo per assassinare il Re\u2026&#8221;<br> &#8220;Andiamo a vedere. Il Comandante Jonhatan e Shadowbreaker sanno il fatto loro&#8221;<br> Evocammo i cavalli e partimmo per dirigerci dall&#8217;altro lato della citt\u00e0. Durante la cavalcata si sentivano urla, grida di battaglia e di morte, e mi sentii un po&#8217; in colpa per quei minuti in cui stavo lasciando l&#8217;esercito in balia di se stesso. Ma raggiungemmo la fortezza e\u2026<br> &#8220;Non \u00e8 possibile!&#8221; url\u00f2 il reggente.<br> Cinque cavalieri della morte erano proprio l\u00ec e stavano assaltando la porta, chiusa, dietro la quale si stava proteggendo la scorta del re. In quel momento, da una via laterale dietro di noi, sbucarono ghoul e abomini.<br> &#8220;Presto!&#8221; dissi, afferrando il braccio del reggente e teletrasportandomi al di l\u00e0 del portone, dritta nella stanza.<br> Ci ritrovammo nella sala che avevo attraversato giorni prima con Naemor, allorch\u00e9 giungemmo per la prima volta a Stormwind. Qui c&#8217;era la guardia elite che stava sorreggendo la porta dagli assalti dei cavalieri della morte.<br> &#8220;Lord Fordragon!&#8221; dissero sbalorditi. &#8220;come\u2026?&#8221;<br> &#8220;Lascia perdere Malagan! Piuttosto cosa sta succedendo qui?&#8221;<br> &#8220;Ci hanno preso di sorpresa! Devono aver aggirato le nostre difese e essere penetrati qui&#8221; rispose quello che sembrava fosse il capitano delle guardie. Io intanto ero stupita della mia stessa genialit\u00e0.<br> &#8220;Comunque prima di teletrasportarci qui sono arrivati rinforzi&#8221; dissi<br> &#8220;Che significa?&#8221;<br> &#8220;Una sola cosa: la battaglia ora sta avvenendo in vari luoghi della citt\u00e0 tra piccole bande scoordinate, penso&#8221;<br> &#8220;E io mi fido, se non era per la tua intuizione\u2026&#8221; disse il reggente.<br> Ma proprio in quel momento si ud\u00ec un ruggito tremendo al di l\u00e0 della porta: erano chiaramente i versi di un abomino.<br> &#8220;La porta non regger\u00e0&#8221; dissi.<br> &#8220;Cosa proponi?&#8221;<br> &#8220;Affrontiamoli, non dovrebbero essere molti. Sosterr\u00f2 la porta con della magia, mentre arretreremo verso il centro della sala: una volta che saremo pronti aprir\u00f2 le porte e ci scontreremo&#8221;<br> &#8220;Va bene.&#8221;<br> E cos\u00ec facemmo: mentre con la magia tramite la staffa reggevo il portone, arretrammo fino alla sala centrale predisponendoci davanti alla porta dietro la quale si trovava il bambino Re. Avevano serrato ottimamente quella porta in modo tale che anche se avessimo perso sarebbe stato difficile per loro abbatterla; ma sarebbe comunque stato meglio sigillarla con della magia\u2026<br> Le botte sul portone erano pi\u00f9 forti che mai.<br> &#8220;Pronti?&#8221; dissi<br> &#8220;Si!&#8221;<br> Allentai la presa e subito la sala fu invasa di mostri. Ricordo solo una cosa: erano tantissimi, molto pi\u00f9 di quanti avessi potuto immaginare. Non ci fu storia. Ancora una volta, come al portale, avevo sbagliato i calcoli, e nonostante cercai di usare quanti pi\u00f9 incantesimi potessi fare, non riuscii ad abbattere i cinque cavalieri della morte che erano in prima fila. Quando iniziammo lo scontro corpo a corpo mi bast\u00f2 una sonora mazzata sulla testa inflittami da due abomini allo stesso tempo per farmi cadere priva di sensi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mi svegliai dopo non so quanto tempo: vidi per prima la luce che filtrava dal portone di un bel sole luminoso\u2026sembrava tutto vuoto. Mi alzai leggermente e mi guardai intorno: tutti gli uomini della scorta erano morti, a terra privi di spirito e sanguinanti, mentre non c&#8217;era il corpo del reggente Fordragon; come temevo, alzai lo sguardo verso la porta che avrebbe dovuto difendere il Re bambino, e quella era a terra in mille pezzi. Dentro si potevano sentire i singhiozzi di una persona adulta che piangeva copiosamente. Mi alzai, carica di tristezza e sensi di colpa, e mi apprestai a vedere una scena dolorosissima: Fordragon, piangendo, reggeva in braccio il corpo esamine di un bambino, che sembrava per\u00f2 stesse dormendo.<br>\n&#8220;Ho cercato\u2026di\u2026proteggerlo\u2026non ci sono riuscito\u2026&#8221; mormor\u00f2 tra le lacrime.<br>\nMi voltai e fissai i corpi dei poveri uomini che erano morti\u2026non riuscii a trattenere le lacrime.<br>\n&#8220;Immagino\u2026&#8221; inizi\u00f2 il reggente &#8220;che abbiano preso tutta la citt\u00e0\u2026.ucciso tutti\u2026.e sono andati via anche\u2026&#8221;<br>\nNon volevo ammetterlo, ma sembrava cos\u00ec. Uscii dalla fortezza: in un primo momento c&#8217;era silenzio totale, non si udiva nulla se non l&#8217;acqua nel canale che sbatteva contro il muro, ma abituandosi man mano il mio orecchio riuscii a percepire uno stridio di lame. Mi raggiunse Fordragon.<br>\n&#8220;Combattono\u2026&#8221; dissi.<br>\n&#8220;Allora, chiunque stia ancora difendendo la sua amata patria, ricever\u00e0 il mio aiuto\u2026sarei dovuto morire prima nella stanza\u2026&#8221; e si lanci\u00f2 verso il suono. Non potei far altro che seguirlo.<br>\nPassammo tra vie e vicoli, trovando, meravigliosamente, pi\u00f9 soldati vivi che morti, ma tutti feriti a tal punto da non poter combattere. Raggiungemmo la piazza principale: sembrava che l&#8217;esercito fosse l\u00ec, o almeno gran parte, ma erano tutti a terra, vivi, ma molto feriti, e le squadre mediche gi\u00e0 si davano da fare; eppure si sentivano urla, grida, lame, come se la battaglia stesse avvenendo proprio l\u00ec.<br>\n&#8220;Che cosa sta succedendo qui?&#8221; mi chiesi.<br>\nFinch\u00e8 si ud\u00ec il suono che meno mi aspettavo di sentire: il corno del Silver Hand. Quello che di solito si sentiva a Theramore alle adunate dell&#8217;Ordine.<br>\n&#8220;Uth..no\u2026cosa??&#8221; mormor\u00f2 il reggente, memore anche lui di quel corno udito chiss\u00e0 in quale epoca.<br>\n&#8220;Non pu\u00f2 essere Naemor\u2026lui \u00e8 morto\u2026deve essere Relhiar!&#8221; urlai.<br>\nArrivammo nella Valle degli Eroi, disastrata dopo il crollo delle mura, che ora si riversavano tutte nel fossato, ma col ponte ancora in piedi. E proprio al confine della citt\u00e0 con la foresta ci davano le spalle le truppe del Re Lich, che stavano combattendo con qualche alleato situato al di la del loro schieramento, che noi non riuscimmo a vedere nonostante avessimo i corpi orrendi dei nemici e non le mura a coprirci la vista.<br>\n&#8220;Dovremmo avvicinarci&#8221; dissi.<br>\n&#8220;No, torniamo indietro, saliremo su quella torre che si regge ancora in piedi&#8221; disse indicando alle sue spalle una torre.<br>\nTornammo indietro nella piazza principale e seguii il reggente lungo alcune strade fino a giungere ai piedi della torre. Salimmo le scale molto velocemente, con in sottofondo ancora queste urla di battaglia e stridii di lame. Salii prima il reggente di me, e lo sentii dire:<br>\n&#8220;E&#8217;\u2026assurdo!&#8221; con un largo gesto delle braccia.<br>\nSalii anche io e guardai. L&#8217;esercito contro cui stava combattendo la legione del Re Lich era semplicemente trasparente. Non c&#8217;era alcun modo di definirlo. Erano fanti e cavalieri umani, che combattevano e che uccidevano, ma erano fantasmi!<br>\n&#8220;Quella armatura\u2026\u00e8 vecchissima\u2026si portava ai tempi della seconda guerra\u2026&#8221;<br>\nIn quella massa grigia, una sola grande macchia azzurra risplendeva in prima fila. Aguzzai la vista e riconobbi gli inconfondibili movimenti di Naemor.<br>\n&#8220;No \u00e8 assurdo\u2026\u00e8 vivo ancora!&#8221; urlai piena di gioia agitando in alto le mani per attendere un segno di risposta. E un ampio grido si diffuse in tutta la vallata:<br>\n&#8220;Doroty!!&#8221;<br>\n&#8220;No non \u00e8 possibile\u2026mi state prendendo in giro\u2026&#8221; mormor\u00f2 il reggente quasi seriamente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Lord Mario<\/h2>\n","protected":false},"excerpt":{"rendered":"<p>A quel punto l&#8217;orda dei non-morti inizi\u00f2 a penetrare nella citt\u00e0, trovando per\u00f2 una strenua difesa: i nostri soldati, compatti, stavano cercando col massimo delle loro forze di resistere. La prima fase della battaglia si svolse tutta nella Valle degli Eroi: i due schieramenti si scontrarono con inaudita violenza per molti minuti, durante i quali ci furono parecchie vittime per ambo i lati. Stormwind riusciva a tenere i non-morti ancora fuori le mura, bench\u00e9 si notasse che col passare del tempo stessero arretrando di poco a poco verso l&#8217;interno. <\/p>\n","protected":false},"author":1,"featured_media":12456,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","footnotes":""},"categories":[7],"tags":[12],"class_list":["post-3139","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-racconti","tag-racconti","latest_post"],"_links":{"self":[{"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/posts\/3139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/comments?post=3139"}],"version-history":[{"count":2,"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/posts\/3139\/revisions"}],"predecessor-version":[{"id":13035,"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/posts\/3139\/revisions\/13035"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/media\/12456"}],"wp:attachment":[{"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/media?parent=3139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/categories?post=3139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.warlandia.it\/magazine\/wp-json\/wp\/v2\/tags?post=3139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}